{"id":70047,"date":"2023-10-30T11:33:30","date_gmt":"2023-10-30T11:33:30","guid":{"rendered":"https:\/\/www.joma-sport.com\/blog\/?p=70047"},"modified":"2023-10-30T11:33:30","modified_gmt":"2023-10-30T11:33:30","slug":"el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia","status":"publish","type":"post","link":"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/","title":{"rendered":"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia"},"content":{"rendered":"<h2>Las Panteras conquistan la Supercopa de Italia ganando 3-1 al Vero Volley Milano.<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Gracias a una actuaci\u00f3n de car\u00e1cter en el partido disputado el s\u00e1bado 28 de octubre en Livorno, Imoco Volley conquista la<strong> Supercopa de Italia 2023<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Se trata de la <strong>s\u00e9ptima Supercopa para las Panteras, la sexta consecutiva<\/strong>, obtenida gracias a la clara victoria sobre uno de los equipos m\u00e1s temibles tambi\u00e9n en clave scudetto 2024. Las Panteras, como siempre vestidas con la <a href=\"https:\/\/www.joma-sport.com\/es_ES\/deporte\/otros-deportes\/voleibol\/\" target=\"_blank\" rel=\"noopener\"><strong>equipaci\u00f3n de Joma<\/strong><\/a>, demostraron estar ya en forma en el primer trofeo en juego de la temporada, con la <strong>capitana Joanna Wo\u0142osz como MVP del partido<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Nuevos retos esperan ahora al #JomaTeam, que saltar\u00e1 al campo en los pr\u00f3ximos d\u00edas tanto en liga como en los primeros partidos internacionales de la CEV Champions League.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Panteras conquistan la Supercopa de Italia ganando 3-1 al Vero Volley Milano. Gracias a una actuaci\u00f3n de car\u00e1cter en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[94],"tags":[73,318],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World\" \/>\n<meta property=\"og:description\" content=\"Las Panteras conquistan la Supercopa de Italia ganando 3-1 al Vero Volley Milano. Gracias a una actuaci\u00f3n de car\u00e1cter en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Joma World\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T11:33:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joma-sport.com\/blog\/wp-content\/uploads\/2023\/10\/noticia_imoco_septima_supercopa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JOMA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"JOMA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/\",\"url\":\"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/\",\"name\":\"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World\",\"isPartOf\":{\"@id\":\"https:\/\/www.joma-sport.com\/blog\/#website\"},\"datePublished\":\"2023-10-30T11:33:30+00:00\",\"dateModified\":\"2023-10-30T11:33:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/#website\",\"url\":\"https:\/\/www.joma-sport.com\/blog\/\",\"name\":\"Joma World\",\"description\":\"Inside Joma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joma-sport.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab\",\"name\":\"JOMA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g\",\"caption\":\"JOMA\"},\"url\":\"https:\/\/www.joma-sport.com\/blog\/author\/jomanews\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/","og_locale":"es_ES","og_type":"article","og_title":"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World","og_description":"Las Panteras conquistan la Supercopa de Italia ganando 3-1 al Vero Volley Milano. Gracias a una actuaci\u00f3n de car\u00e1cter en [&hellip;]","og_url":"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/","og_site_name":"Joma World","article_published_time":"2023-10-30T11:33:30+00:00","og_image":[{"width":696,"height":518,"url":"https:\/\/www.joma-sport.com\/blog\/wp-content\/uploads\/2023\/10\/noticia_imoco_septima_supercopa.jpg","type":"image\/jpeg"}],"author":"JOMA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"JOMA","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/","url":"https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/","name":"El #JomaTeam Imoco Voley conquista su s\u00e9ptima Supercopa de Italia - Joma World","isPartOf":{"@id":"https:\/\/www.joma-sport.com\/blog\/#website"},"datePublished":"2023-10-30T11:33:30+00:00","dateModified":"2023-10-30T11:33:30+00:00","author":{"@id":"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joma-sport.com\/blog\/el-jomateam-imoco-voley-conquista-su-septima-supercopa-de-italia\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.joma-sport.com\/blog\/#website","url":"https:\/\/www.joma-sport.com\/blog\/","name":"Joma World","description":"Inside Joma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joma-sport.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab","name":"JOMA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joma-sport.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g","caption":"JOMA"},"url":"https:\/\/www.joma-sport.com\/blog\/author\/jomanews\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/posts\/70047"}],"collection":[{"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/comments?post=70047"}],"version-history":[{"count":1,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/posts\/70047\/revisions"}],"predecessor-version":[{"id":70057,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/posts\/70047\/revisions\/70057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/media\/70048"}],"wp:attachment":[{"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/media?parent=70047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/categories?post=70047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/wp-json\/wp\/v2\/tags?post=70047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}