{"id":57019,"date":"2021-08-01T13:00:00","date_gmt":"2021-08-01T13:00:00","guid":{"rendered":"https:\/\/www.joma-sport.com\/blog\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/"},"modified":"2021-08-01T13:00:00","modified_gmt":"2021-08-01T13:00:00","slug":"le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor","status":"publish","type":"post","link":"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/","title":{"rendered":"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor"},"content":{"rendered":"<p>Ferrao, le joueur de futsal du FC Barcelone et titulaire indiscutable au sein de l&rsquo;&eacute;quipe nationale du Br&eacute;sil, est la nouvelle star de la Team Joma. Le Br&eacute;silien et la marque espagnole s&rsquo;associent pour les prochaines ann&eacute;es&nbsp;en concluant un partenariat technique&nbsp;: Joma devient l&rsquo;&eacute;quipementier du joueur pour les chaussures et les v&ecirc;tements.<\/p>\n<p>&nbsp;<\/p>\n<p>Ferrao poss&egrave;de un riche palmar&egrave;s au niveau personnel comme en club. Il a &eacute;t&eacute; &eacute;lu meilleur joueur du monde &agrave; deux reprises, la derni&egrave;re fois en 2021, lors des Futsalplanet, les r&eacute;compenses d&eacute;cern&eacute;es chaque ann&eacute;e dans le monde du futsal. Il a &eacute;galement re&ccedil;u le prix du meilleur joueur de la LNFS, du meilleur pivot et du meilleur buteur &agrave; trois reprises.<\/p>\n<p>En club, il a &eacute;t&eacute; champion de l&rsquo;UEFA Futsal Champions League et a remport&eacute; toutes les comp&eacute;titions espagnoles : trois Coupes du Roi, deux Coupes d&rsquo;Espagne, une Supercoupe d&rsquo;Espagne et une Liga.<\/p>\n<p>Capitaine de la s&eacute;lection br&eacute;silienne, quintuple championne du monde, Ferrao disputera sa premi&egrave;re comp&eacute;tition officielle sous les couleurs de Joma lors de la prochaine Coupe du monde en Lituanie qui d&eacute;butera le 12 septembre prochain.<\/p>\n<p>Ferrao est un joueur athl&eacute;tique dont la pr&eacute;sence physique et le jeu tr&egrave;s vertical apportent un &eacute;quilibre &agrave; son &eacute;quipe. &Eacute;tant donn&eacute; ses caract&eacute;ristiques, il a choisi de porter les Regate Rebound car c&rsquo;est le mod&egrave;le de Joma offrant le meilleur amorti et la plus grande r&eacute;activit&eacute;. Ces chaussures utilisent la technologie REACTIVE BALL permettant d&rsquo;absorber l&rsquo;impact de la foul&eacute;e et de favoriser une relance plus r&eacute;active.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le meilleur joueur du monde de futsal portera d\u00e9sormais les chaussures de la marque espagnole.<\/p>\n","protected":false},"author":1,"featured_media":27191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[178,184],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World\" \/>\n<meta property=\"og:description\" content=\"Le meilleur joueur du monde de futsal portera d\u00e9sormais les chaussures de la marque espagnole.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/\" \/>\n<meta property=\"og:site_name\" content=\"Joma World\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-01T13:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joma-sport.com\/blog\/wp-content\/uploads\/2021\/08\/20210729_171413_noticia-ferrao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JOMA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"JOMA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/\",\"url\":\"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/\",\"name\":\"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World\",\"isPartOf\":{\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/#website\"},\"datePublished\":\"2021-08-01T13:00:00+00:00\",\"dateModified\":\"2021-08-01T13:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/#website\",\"url\":\"https:\/\/www.joma-sport.com\/blog\/fr\/\",\"name\":\"Joma World\",\"description\":\"Inside Joma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joma-sport.com\/blog\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab\",\"name\":\"JOMA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g\",\"caption\":\"JOMA\"},\"url\":\"https:\/\/www.joma-sport.com\/blog\/fr\/author\/jomanews\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World","og_description":"Le meilleur joueur du monde de futsal portera d\u00e9sormais les chaussures de la marque espagnole.","og_url":"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/","og_site_name":"Joma World","article_published_time":"2021-08-01T13:00:00+00:00","og_image":[{"width":696,"height":518,"url":"https:\/\/www.joma-sport.com\/blog\/wp-content\/uploads\/2021\/08\/20210729_171413_noticia-ferrao.jpg","type":"image\/jpeg"}],"author":"JOMA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"JOMA","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/","url":"https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/","name":"Le Br\u00e9silien Ferrao accorde sa confiance \u00e0 Joma, son nouveau sponsor - Joma World","isPartOf":{"@id":"https:\/\/www.joma-sport.com\/blog\/fr\/#website"},"datePublished":"2021-08-01T13:00:00+00:00","dateModified":"2021-08-01T13:00:00+00:00","author":{"@id":"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joma-sport.com\/blog\/fr\/le-bresilien-ferrao-accorde-sa-confiance-a-joma-son-nouveau-sponsor\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.joma-sport.com\/blog\/fr\/#website","url":"https:\/\/www.joma-sport.com\/blog\/fr\/","name":"Joma World","description":"Inside Joma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joma-sport.com\/blog\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/8467085eeea397781a9e5a5bd0211eab","name":"JOMA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joma-sport.com\/blog\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e6444480edb84ebaf5afa2a3a5cea7e?s=96&d=mm&r=g","caption":"JOMA"},"url":"https:\/\/www.joma-sport.com\/blog\/fr\/author\/jomanews\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/57019"}],"collection":[{"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=57019"}],"version-history":[{"count":0,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/57019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/media\/27191"}],"wp:attachment":[{"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=57019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=57019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joma-sport.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=57019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}